{"id":19642,"date":"2023-01-28T19:07:51","date_gmt":"2023-01-28T22:07:51","guid":{"rendered":"https:\/\/awzorquideas.com.br\/web\/produto\/l-praestans-concolor-x-concolor-sao-gabriel\/"},"modified":"2026-08-25T12:32:22","modified_gmt":"2026-08-25T15:32:22","slug":"l-praestans-concolor-x-concolor-sao-gabriel","status":"publish","type":"product","link":"https:\/\/awzorquideas.com.br\/web\/en\/product\/l-praestans-concolor-x-concolor-sao-gabriel\/","title":{"rendered":"LC. Ericoi (L. praestans concolor x C. warneri concolor)"},"content":{"rendered":"<p><b>C\u00d3DIGO:<\/b> Z-3756<br \/><b>GRUPO:<\/b> H\u00cdBRIDOS \/ HYBRIDS<br \/><b>VASO \/ POT SIZE:<\/b> 2 1\/2&#8243;<br \/><b>DESCRI\u00c7\u00c3O:<\/b> <br \/><b>DESCRIPTION:<\/b><\/p>","protected":false},"excerpt":{"rendered":"<p>C\u00d3DIGO: Z-3756GRUPO: H\u00cdBRIDOS \/ HYBRIDSVASO \/ POT SIZE: 2 1\/2&#8243;DESCRI\u00c7\u00c3O: DESCRIPTION:<\/p>","protected":false},"featured_media":21469,"template":"","meta":[],"product_brand":[1174],"product_cat":[82],"product_tag":[458],"class_list":["post-19642","product","type-product","status-publish","has-post-thumbnail","product_brand-ed","product_cat-hibridos-hybrids","product_tag-brasil-usa","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/product\/19642","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/media\/21469"}],"wp:attachment":[{"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/media?parent=19642"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/product_brand?post=19642"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/product_cat?post=19642"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/en\/wp-json\/wp\/v2\/product_tag?post=19642"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}