{"id":19586,"date":"2024-07-17T20:39:28","date_gmt":"2024-07-17T23:39:28","guid":{"rendered":"https:\/\/awzorquideas.com.br\/web\/produto\/c-warneri-carminha-x-suavissima-nego\/"},"modified":"2026-08-21T20:26:42","modified_gmt":"2026-08-21T23:26:42","slug":"c-warneri-carminha-x-suavissima-nego","status":"publish","type":"product","link":"https:\/\/awzorquideas.com.br\/web\/produto\/c-warneri-carminha-x-suavissima-nego\/","title":{"rendered":"C. warneri (&#8216;Carminha&#8217; x suavissima &#8216;Nego&#8217;)"},"content":{"rendered":"<p><b>C\u00d3DIGO:<\/b> Z-3762<br \/><b>GRUPO:<\/b> C. warneri<br \/><b>VASO \/ POT SIZE:<\/b> 2 1\/2&#8243;<br \/><b>DESCRI\u00c7\u00c3O:<\/b> <br \/><b>DESCRIPTION:<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u00d3DIGO: Z-3762GRUPO: C. warneriVASO \/ POT SIZE: 2 1\/2&#8243;DESCRI\u00c7\u00c3O: DESCRIPTION:<\/p>\n","protected":false},"featured_media":21008,"template":"","meta":[],"product_brand":[1174],"product_cat":[64],"product_tag":[458],"class_list":["post-19586","product","type-product","status-publish","has-post-thumbnail","product_brand-ed","product_cat-c-warneri","product_tag-brasil-usa","first","instock","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/product\/19586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/media\/21008"}],"wp:attachment":[{"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/media?parent=19586"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/product_brand?post=19586"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/product_cat?post=19586"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/awzorquideas.com.br\/web\/wp-json\/wp\/v2\/product_tag?post=19586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}